{"id":998,"date":"2018-07-14T21:34:17","date_gmt":"2018-07-14T19:34:17","guid":{"rendered":"https:\/\/kirche-hettenhausen.de\/site\/?p=998"},"modified":"2021-02-16T21:47:44","modified_gmt":"2021-02-16T20:47:44","slug":"neues-vom-friedhof","status":"publish","type":"post","link":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/","title":{"rendered":"Neues vom Friedhof"},"content":{"rendered":"<p>Die Arbeiten an der zus\u00e4tzlichen Wasserzapfstelle am hinteren Urnenfeld wurden im Fr\u00fchjahr 2018 abgeschlossen. Somit verf\u00fcgt der \u201eneue\u201c Teil des Friedhofs nun \u00fcber ein engmaschiges Netz an Wasserstellen, die das Bew\u00e4ssern der Grabst\u00e4tten in dem Bereich so bequem wie m\u00f6glich machen.<\/p>\n<p>Vielen Dank nochmals f\u00fcr die gro\u00dfz\u00fcgigen Spenden, die dieses Projekt erst m\u00f6glich gemacht haben, sei es in Form von Geldspenden, Kollekten oder Sachleistungen. Die Arbeiten wurden durch Firma Hack, Hettenhausen sowie Firma Simon Heizungsbau, Hettenhausen, weitgehend unentgeltlich in Form einer Spende f\u00fcr die Kirchengemeinde durchgef\u00fchrt.<\/p>\n<p>&nbsp;<\/p>\n<p>Seit dem 24. Mai 2016 sind f\u00fcr den Friedhof in Hettenhausen sowohl eine \u00fcberarbeitete <a href=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2016\/06\/Friedhofsordnung-2016.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Friedhofsordnung<\/a> als auch\u00a0<a href=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2016\/06\/Friedhofsgeb\u00fchrenordnung-2016.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Friedhofsgeb\u00fchrenordnung<\/a>\u00a0in Kraft getreten.<\/p>\n<p>Weiterhin wurden zwischenzeitlich die Bauma\u00dfnahmen am hinteren Friedhofseingang mit neuem Tor und den Pflasterarbeiten in diesem Bereich abgeschlossen. Der Schl\u00fcssel f\u00fcr das Friedhofstor ist im Bedarfsfall bei Gernot Schleitzer erh\u00e4ltlich.<\/p>\n<p>Ein herzliches Dankesch\u00f6n geht an die Konfirmierten des Jahrgangs 2016, die die neue Bank auf dem Friedhof spendeten.<\/p>\n<p>Desweiteren bedanken wir uns f\u00fcr die Spende der Jubil\u00e4umskonfirmanden 2016 in H\u00f6he von 395,00\u00a0\u20ac. Diese Spende ist f\u00fcr die Einrichtung einer zus\u00e4tzlichen Wasserzapfstelle bei den Urnengr\u00e4bern am Friedhof bestimmt.<\/p>\n<p>Gez. Die Friedhofsverwaltung<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">(mf)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Arbeiten an der zus\u00e4tzlichen Wasserzapfstelle am hinteren Urnenfeld wurden im Fr\u00fchjahr 2018 abgeschlossen. Somit verf\u00fcgt der \u201eneue\u201c Teil des Friedhofs nun \u00fcber ein engmaschiges Netz an Wasserstellen, die das Bew\u00e4ssern der Grabst\u00e4tten in dem Bereich so bequem wie m\u00f6glich machen. Vielen Dank nochmals f\u00fcr die gro\u00dfz\u00fcgigen Spenden, die dieses Projekt erst m\u00f6glich gemacht haben, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":997,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,129,76],"tags":[35,128,77],"class_list":["post-998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-friedhof","category-hettenhausen","category-kirchenvorstand","tag-friedhof","tag-hettenhausen","tag-kirchenvorstand"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neues vom Friedhof - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neues vom Friedhof - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"og:description\" content=\"Die Arbeiten an der zus\u00e4tzlichen Wasserzapfstelle am hinteren Urnenfeld wurden im Fr\u00fchjahr 2018 abgeschlossen. Somit verf\u00fcgt der \u201eneue\u201c Teil des Friedhofs nun \u00fcber ein engmaschiges Netz an Wasserstellen, die das Bew\u00e4ssern der Grabst\u00e4tten in dem Bereich so bequem wie m\u00f6glich machen. Vielen Dank nochmals f\u00fcr die gro\u00dfz\u00fcgigen Spenden, die dieses Projekt erst m\u00f6glich gemacht haben, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/\" \/>\n<meta property=\"og:site_name\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-14T19:34:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-16T20:47:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2016\/07\/20160715_181011_1-e1478020414549.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"448\" \/>\n\t<meta property=\"og:image:height\" content=\"252\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marion Friedrich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marion Friedrich\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/\"},\"author\":{\"name\":\"Marion Friedrich\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#\\\/schema\\\/person\\\/7740d89d8f816da861ece2b378a21c57\"},\"headline\":\"Neues vom Friedhof\",\"datePublished\":\"2018-07-14T19:34:17+00:00\",\"dateModified\":\"2021-02-16T20:47:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/\"},\"wordCount\":212,\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/20160715_181011_1-e1478020414549.jpg\",\"keywords\":[\"Friedhof\",\"Hettenhausen\",\"Kirchenvorstand\"],\"articleSection\":[\"Friedhof\",\"Hettenhausen\",\"Kirchenvorstand\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/\",\"name\":\"Neues vom Friedhof - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/20160715_181011_1-e1478020414549.jpg\",\"datePublished\":\"2018-07-14T19:34:17+00:00\",\"dateModified\":\"2021-02-16T20:47:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#\\\/schema\\\/person\\\/7740d89d8f816da861ece2b378a21c57\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/20160715_181011_1-e1478020414549.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/20160715_181011_1-e1478020414549.jpg\",\"width\":448,\"height\":252},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2018\\\/07\\\/neues-vom-friedhof\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neues vom Friedhof\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\",\"name\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"description\":\"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#\\\/schema\\\/person\\\/7740d89d8f816da861ece2b378a21c57\",\"name\":\"Marion Friedrich\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/author\\\/m-friedrichkirche-hettenhausen-de\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neues vom Friedhof - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/","og_locale":"de_DE","og_type":"article","og_title":"Neues vom Friedhof - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","og_description":"Die Arbeiten an der zus\u00e4tzlichen Wasserzapfstelle am hinteren Urnenfeld wurden im Fr\u00fchjahr 2018 abgeschlossen. Somit verf\u00fcgt der \u201eneue\u201c Teil des Friedhofs nun \u00fcber ein engmaschiges Netz an Wasserstellen, die das Bew\u00e4ssern der Grabst\u00e4tten in dem Bereich so bequem wie m\u00f6glich machen. Vielen Dank nochmals f\u00fcr die gro\u00dfz\u00fcgigen Spenden, die dieses Projekt erst m\u00f6glich gemacht haben, [&hellip;]","og_url":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/","og_site_name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","article_published_time":"2018-07-14T19:34:17+00:00","article_modified_time":"2021-02-16T20:47:44+00:00","og_image":[{"width":448,"height":252,"url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2016\/07\/20160715_181011_1-e1478020414549.jpg","type":"image\/jpeg"}],"author":"Marion Friedrich","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Marion Friedrich","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/#article","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/"},"author":{"name":"Marion Friedrich","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#\/schema\/person\/7740d89d8f816da861ece2b378a21c57"},"headline":"Neues vom Friedhof","datePublished":"2018-07-14T19:34:17+00:00","dateModified":"2021-02-16T20:47:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/"},"wordCount":212,"image":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2016\/07\/20160715_181011_1-e1478020414549.jpg","keywords":["Friedhof","Hettenhausen","Kirchenvorstand"],"articleSection":["Friedhof","Hettenhausen","Kirchenvorstand"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/","url":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/","name":"Neues vom Friedhof - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2016\/07\/20160715_181011_1-e1478020414549.jpg","datePublished":"2018-07-14T19:34:17+00:00","dateModified":"2021-02-16T20:47:44+00:00","author":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#\/schema\/person\/7740d89d8f816da861ece2b378a21c57"},"breadcrumb":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/#primaryimage","url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2016\/07\/20160715_181011_1-e1478020414549.jpg","contentUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2016\/07\/20160715_181011_1-e1478020414549.jpg","width":448,"height":252},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2018\/07\/neues-vom-friedhof\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-hettenhausen.de\/site\/"},{"@type":"ListItem","position":2,"name":"Neues vom Friedhof"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website","url":"https:\/\/www.kirche-hettenhausen.de\/site\/","name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-hettenhausen.de\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#\/schema\/person\/7740d89d8f816da861ece2b378a21c57","name":"Marion Friedrich","url":"https:\/\/www.kirche-hettenhausen.de\/site\/author\/m-friedrichkirche-hettenhausen-de\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/posts\/998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/comments?post=998"}],"version-history":[{"count":10,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/posts\/998\/revisions"}],"predecessor-version":[{"id":4948,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/posts\/998\/revisions\/4948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media\/997"}],"wp:attachment":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media?parent=998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/categories?post=998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/tags?post=998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}