{"id":7029,"date":"2021-01-15T22:34:10","date_gmt":"2021-01-15T21:34:10","guid":{"rendered":"https:\/\/kirche-hettenhausen.de\/site\/?p=7029"},"modified":"2026-03-20T11:50:58","modified_gmt":"2026-03-20T10:50:58","slug":"bericht-von-der-kreissynode","status":"publish","type":"post","link":"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/","title":{"rendered":"Bericht von der Kreissynode"},"content":{"rendered":"<p>Am 1. Oktober 2020 traf sich nach der Kirchenvorstandswahl im September 2019 zum ersten Mal die Kreissynode zu einer konstituierenden Sitzung.<\/p>\n<p>Die Kreissynode ist das oberste Entscheidungsorgan in der Evangelischen Kirche auf kreiskirchlicher Ebene und tagt in der Regel zweimal j\u00e4hrlich. Jede Kirchengemeinde entsendet zwei Vertreter (Synodale) neben dem Pfarrer in die Synode; f\u00fcr unsere Gemeinde sind dies Marion Friedrich und Martin Schleicher, als Vertreter Verena Frohnapfel und Simone Ke\u00dfler. Der Synode geh\u00f6ren dar\u00fcber hinaus zus\u00e4tzlich berufene Mitglieder an. In der Synode werden gemeinde\u00fcbergreifende Themen behandelt und richtungsweisende Entscheidungen getroffen, z. B. die Haushalts- und Stellenplanung im Kirchenkreis oder auch die notwendige Pfarrstellenanpassung. Wichtige Themen waren und sind dar\u00fcber hinaus die Diakonie, die Telefonseelsorge, Kinder- und Jugendarbeit, Kirchenmusik und die Kooperationsr\u00e4ume im Kirchenkreis.<\/p>\n<p>Folgende Synodale wurden in den Kirchenkreisvorstand gew\u00e4hlt:<\/p>\n<table style=\"width: 99.5896%;\" width=\"523\">\n<tbody>\n<tr>\n<td style=\"width: 49.1786%;\" width=\"291\">Vorsitzender der Kreissynode:<\/td>\n<td style=\"width: 139.831%;\" width=\"232\">Andreas Maraun<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 49.1786%;\" width=\"291\">stellv. Vorsitzender:<\/td>\n<td style=\"width: 139.831%;\" width=\"232\">Pfr. Marvin Lange<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 49.1786%;\" width=\"291\">1. geistliches Mitglied (Dekan):<\/td>\n<td style=\"width: 139.831%;\" width=\"232\">Bengt Seeberg<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 49.1786%;\" width=\"291\">2. geistliches Mitglied (stellv. Dekan):<\/td>\n<td style=\"width: 139.831%;\" width=\"232\">Pfr. Marvin Lange<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 49.1786%;\" width=\"291\">Stellvertreter des 2. geistlichen Mitglieds:<\/td>\n<td style=\"width: 139.831%;\" width=\"232\">Pfr. Karl Josef Gruber<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 49.1786%;\" width=\"291\">1. Laienmitglied:<\/td>\n<td style=\"width: 139.831%;\" width=\"232\">Christine Hain<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 49.1786%;\" width=\"291\">2. Laienmitglied:<\/td>\n<td style=\"width: 139.831%;\" width=\"232\">Margrit Steiner<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 49.1786%;\" width=\"291\">Stellvertreter des 1. Laienmitglieds:<\/td>\n<td style=\"width: 139.831%;\" width=\"232\">Bernhard Simon<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 49.1786%;\" width=\"291\">Stellvertreterin des 2. Laienmitglieds:<\/td>\n<td style=\"width: 139.831%;\" width=\"232\">Michaela Beck<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Au\u00dferdem wurden Vertreter in die verschiedenen Aussch\u00fcsse gew\u00e4hlt; u.\u00a0a. S\u00f6ren Scharf aus Hettenhausen f\u00fcr den Kooperationsraum Rh\u00f6n in den Kinder- und Jugendausschuss.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">(mf)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 1. Oktober 2020 traf sich nach der Kirchenvorstandswahl im September 2019 zum ersten Mal die Kreissynode zu einer konstituierenden Sitzung. Die Kreissynode ist das oberste Entscheidungsorgan in der Evangelischen Kirche auf kreiskirchlicher Ebene und tagt in der Regel zweimal j\u00e4hrlich. Jede Kirchengemeinde entsendet zwei Vertreter (Synodale) neben dem Pfarrer in die Synode; f\u00fcr unsere [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,76,24,97],"tags":[101,28,219,77,30,98,7],"class_list":["post-7029","post","type-post","status-publish","format-standard","hentry","category-kirchen-kurier","category-kirchenvorstand","category-kooperationsraum-rhoen","category-landeskirche","tag-jugend","tag-kinder","tag-kirchenkreis-fulda","tag-kirchenvorstand","tag-kooperationsraum-rhoen","tag-landeskirche","tag-pfarrer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bericht von der Kreissynode - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda<\/title>\n<meta name=\"description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Bericht von der Kreissynode -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bericht von der Kreissynode - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"og:description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Bericht von der Kreissynode -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/\" \/>\n<meta property=\"og:site_name\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-15T21:34:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T10:50:58+00:00\" \/>\n<meta name=\"author\" content=\"Marion Friedrich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marion Friedrich\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2021\\\/01\\\/bericht-von-der-kreissynode\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2021\\\/01\\\/bericht-von-der-kreissynode\\\/\"},\"author\":{\"name\":\"Marion Friedrich\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#\\\/schema\\\/person\\\/7740d89d8f816da861ece2b378a21c57\"},\"headline\":\"Bericht von der Kreissynode\",\"datePublished\":\"2021-01-15T21:34:10+00:00\",\"dateModified\":\"2026-03-20T10:50:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2021\\\/01\\\/bericht-von-der-kreissynode\\\/\"},\"wordCount\":219,\"keywords\":[\"Jugend\",\"Kinder\",\"Kirchenkreis Fulda\",\"Kirchenvorstand\",\"Kooperationsraum Rh\u00f6n\",\"Landeskirche\",\"Pfarrer\"],\"articleSection\":[\"Kirchen-Kurier\",\"Kirchenvorstand\",\"Kooperationsraum Rh\u00f6n\",\"Landeskirche\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2021\\\/01\\\/bericht-von-der-kreissynode\\\/\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2021\\\/01\\\/bericht-von-der-kreissynode\\\/\",\"name\":\"Bericht von der Kreissynode - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\"},\"datePublished\":\"2021-01-15T21:34:10+00:00\",\"dateModified\":\"2026-03-20T10:50:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#\\\/schema\\\/person\\\/7740d89d8f816da861ece2b378a21c57\"},\"description\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Bericht von der Kreissynode -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2021\\\/01\\\/bericht-von-der-kreissynode\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2021\\\/01\\\/bericht-von-der-kreissynode\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/2021\\\/01\\\/bericht-von-der-kreissynode\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bericht von der Kreissynode\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\",\"name\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"description\":\"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#\\\/schema\\\/person\\\/7740d89d8f816da861ece2b378a21c57\",\"name\":\"Marion Friedrich\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/author\\\/m-friedrichkirche-hettenhausen-de\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bericht von der Kreissynode - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Bericht von der Kreissynode -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/","og_locale":"de_DE","og_type":"article","og_title":"Bericht von der Kreissynode - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","og_description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Bericht von der Kreissynode -","og_url":"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/","og_site_name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","article_published_time":"2021-01-15T21:34:10+00:00","article_modified_time":"2026-03-20T10:50:58+00:00","author":"Marion Friedrich","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Marion Friedrich","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/#article","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/"},"author":{"name":"Marion Friedrich","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#\/schema\/person\/7740d89d8f816da861ece2b378a21c57"},"headline":"Bericht von der Kreissynode","datePublished":"2021-01-15T21:34:10+00:00","dateModified":"2026-03-20T10:50:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/"},"wordCount":219,"keywords":["Jugend","Kinder","Kirchenkreis Fulda","Kirchenvorstand","Kooperationsraum Rh\u00f6n","Landeskirche","Pfarrer"],"articleSection":["Kirchen-Kurier","Kirchenvorstand","Kooperationsraum Rh\u00f6n","Landeskirche"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/","url":"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/","name":"Bericht von der Kreissynode - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website"},"datePublished":"2021-01-15T21:34:10+00:00","dateModified":"2026-03-20T10:50:58+00:00","author":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#\/schema\/person\/7740d89d8f816da861ece2b378a21c57"},"description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Bericht von der Kreissynode -","breadcrumb":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/01\/bericht-von-der-kreissynode\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-hettenhausen.de\/site\/"},{"@type":"ListItem","position":2,"name":"Bericht von der Kreissynode"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website","url":"https:\/\/www.kirche-hettenhausen.de\/site\/","name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-hettenhausen.de\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#\/schema\/person\/7740d89d8f816da861ece2b378a21c57","name":"Marion Friedrich","url":"https:\/\/www.kirche-hettenhausen.de\/site\/author\/m-friedrichkirche-hettenhausen-de\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/posts\/7029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/comments?post=7029"}],"version-history":[{"count":3,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/posts\/7029\/revisions"}],"predecessor-version":[{"id":7077,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/posts\/7029\/revisions\/7077"}],"wp:attachment":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media?parent=7029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/categories?post=7029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/tags?post=7029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}