{"id":17611,"date":"2026-05-30T21:40:57","date_gmt":"2026-05-30T19:40:57","guid":{"rendered":"https:\/\/www.kirche-hettenhausen.de\/site\/?page_id=17611"},"modified":"2026-05-31T12:32:10","modified_gmt":"2026-05-31T10:32:10","slug":"orgel","status":"publish","type":"page","link":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/","title":{"rendered":"Orgel"},"content":{"rendered":"<p>\u27a1\u00a0 Die urspr\u00fcngliche Orgel stammt vermutlich aus dem Jahr 1670.<\/p>\n<p>\u27a1\u00a0 <strong>1851\u00a0<\/strong> Orgelbauer Ludwig Ratzmann aus dem th\u00fcringischem Ohrdruf baut eine neue Orgel mit 13 Registern, einem Manual und Pedal.<\/p>\n<p>\u27a1\u00a0 <b>1946<\/b>\u00a0 Die Orgel ist fast vollst\u00e4ndig zerst\u00f6rt, Werner Bosch (Kassel) \u00fcberholt die Ratzmann-Orgel.<\/p>\n<p>\u27a1\u00a0 Die Orgel wurde 1965 in einen \u201eunw\u00fcrdigen Zustand der Modernisierung\u201c gebracht und letztlich 1982 stillgelegt.<\/p>\n<p>\u27a1\u00a0 <b>1982<\/b>\u00a0 Einweihung der elektronischen Orgel von der Firma Allan, Ost-Pennsylvania, USA<br \/>\n(Schwellwerk 15, Hauptwerk 14, Pedal, 11 Register, dazu 56 Setzerkombinationen)<\/p>\n<p>\u27a1\u00a0 <strong>1990 <\/strong>\u00a0ergreift Pfarrer Gro\u00dfke erste Renovierungsarbeiten der alten Orgel durch Firma Hoffmann aus Ostheim (Rh\u00f6n). Die Orgel wird aufwendig restauriert sowie rekonstruiert und erklingt wieder in ihrem urspr\u00fcnglichen Zustand.<\/p>\n<p>\u27a1\u00a0 <b>2002<\/b>\u00a0 Eine Holzwurmbek\u00e4mpfung in der Kirche schl\u00e4gt fehl und die Orgel wird stark besch\u00e4digt.<\/p>\n<p>\u27a1\u00a0 <b>2004\u00a0<\/b> Kirche und Orgel k\u00f6nnen wieder in Betrieb genommen werden.<br \/>\n<strong><a href=\"https:\/\/osthessen-news.de\/n8636\/gersfeld-vergiftete-evangelische-kirche-dalherda-heute-wieder-eingeweiht.html\" target=\"_blank\" rel=\"noopener\">&#8222;Vergiftete&#8220; evangelische Kirche Dalherda heute wieder eingeweiht \/\/ Osthessen|News<\/a><\/strong><\/p>\n<p>\u27a1\u00a0 <strong>2025<\/strong>\u00a0 Teilrestaurierung nach Wasserschaden durch Firma Hoffmann &amp; Schindler, Ostheim (Rh\u00f6n)<\/p>\n<p>&nbsp;<\/p>\n<div id=\"metaslider-id-17622\" style=\"width: 100%;\" class=\"ml-slider-3-110-0 metaslider metaslider-flex metaslider-17622 ml-slider has-dots-onhover-navigation ms-theme-default-base\" role=\"region\" aria-label=\"Orgel Dalherda\" data-height=\"1000\" data-width=\"600\">\n    <div id=\"metaslider_container_17622\">\n        <div id=\"metaslider_17622\">\n            <ul aria-live='off' class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-17623 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"Kirche-Dalherda-Innenraum-600x1000.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/Kirche-Dalherda-Innenraum-600x1000.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17623 msDefaultImage\" title=\"Kirche Dalherda Innenraum\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17625 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"IMG-20210519-WA0016-600x1000.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0016-600x1000.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17625 msDefaultImage\" title=\"Orgel Dalherda\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17624 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"IMG-20210519-WA0007-600x1000.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0007-600x1000.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17624 msDefaultImage\" title=\"Orgel Dalherda\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17626 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"IMG-20210519-WA0029-600x1000.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0029-600x1000.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17626 msDefaultImage\" title=\"Orgel Dalherda\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17631 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"IMG-20210519-WA0037-600x1000.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0037-600x1000.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17631 msDefaultImage\" title=\"Orgel Dalherda\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17627 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"IMG-20210519-WA0038-600x1000.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0038-600x1000.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17627 msDefaultImage\" title=\"Orgel Dalherda\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17628 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"IMG-20210519-WA0036-600x1000.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0036-600x1000.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17628 msDefaultImage\" title=\"Orgel Dalherda\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17640 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"IMG-20210519-WA0003-600x1000.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0003-600x1000.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17640 msDefaultImage\" title=\"Orgel Dalherda\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17633 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"IMG-20210519-WA0014-600x1000.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0014-600x1000.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17633 msDefaultImage\" title=\"Orgel Dalherda\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17637 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"IMG-20210519-WA0009-540x900.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0009-540x900.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17637 msDefaultImage\" title=\"Orgel Dalherda\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17639 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"IMG-20210519-WA0006-600x1000.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0006-600x1000.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17639 msDefaultImage\" title=\"Orgel Dalherda\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-17641 ms-image \" aria-roledescription=\"slide\" data-date=\"2026-05-30 20:02:36\" data-filename=\"IMG-20210519-WA0000-600x1000.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0000-600x1000.jpg\" height=\"1000\" width=\"600\" alt=\"\" class=\"slider-17622 slide-17641 msDefaultImage\" title=\"Orgel Dalherda\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<hr \/>\n<p style=\"text-align: center;\">_______________________________________________<\/p>\n<p>(u. a. aus der Chronik von Hettenhausen anl\u00e4sslich des 1050-j\u00e4hrigen Bestehens im Jahr 2006, nach den Aufzeichnungen des Chronisten Friedrich Waldschmidt, Hettenhausen, dem Heimatbuch Dalherda zum 650-j\u00e4hrigen Bestehen sowie aus der Chronik der Kirchengemeinde Dalherda-Poppenhausen mit Aufzeichnungen von Edzard Kr\u00fcckeberg)<\/p>\n<p>\u201eDalherda, Fulda\u201c, in: Historisches Ortslexikon<br \/>\n<a href=\"https:\/\/lagis.hessen.de\/de\/orte\/historisches-ortslexikon\/alle-eintraege\/5499_dalherda\" data-spa=\"1\">https:\/\/lagis.hessen.de\/de\/orte\/historisches-ortslexikon\/alle-eintraege\/5499_dalherda<\/a><\/p>\n<p><a href=\"https:\/\/de.wikipedia.org\/wiki\/Kirche_Dalherda\" target=\"_blank\" rel=\"noopener\">Kirche Dalherda \u2013 Wikipedia<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u27a1\u00a0 Die urspr\u00fcngliche Orgel stammt vermutlich aus dem Jahr 1670. \u27a1\u00a0 1851\u00a0 Orgelbauer Ludwig Ratzmann aus dem th\u00fcringischem Ohrdruf baut eine neue Orgel mit 13 Registern, einem Manual und Pedal. \u27a1\u00a0 1946\u00a0 Die Orgel ist fast vollst\u00e4ndig zerst\u00f6rt, Werner Bosch (Kassel) \u00fcberholt die Ratzmann-Orgel. \u27a1\u00a0 Die Orgel wurde 1965 in einen \u201eunw\u00fcrdigen Zustand der Modernisierung\u201c [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9023,"parent":6775,"menu_order":30,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-17611","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orgel - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orgel - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"og:description\" content=\"\u27a1\u00a0 Die urspr\u00fcngliche Orgel stammt vermutlich aus dem Jahr 1670. \u27a1\u00a0 1851\u00a0 Orgelbauer Ludwig Ratzmann aus dem th\u00fcringischem Ohrdruf baut eine neue Orgel mit 13 Registern, einem Manual und Pedal. \u27a1\u00a0 1946\u00a0 Die Orgel ist fast vollst\u00e4ndig zerst\u00f6rt, Werner Bosch (Kassel) \u00fcberholt die Ratzmann-Orgel. \u27a1\u00a0 Die Orgel wurde 1965 in einen \u201eunw\u00fcrdigen Zustand der Modernisierung\u201c [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/\" \/>\n<meta property=\"og:site_name\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-31T10:32:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0011.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/unsere-kirchen\\\/kirche-dalherda\\\/orgel\\\/\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/unsere-kirchen\\\/kirche-dalherda\\\/orgel\\\/\",\"name\":\"Orgel - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/unsere-kirchen\\\/kirche-dalherda\\\/orgel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/unsere-kirchen\\\/kirche-dalherda\\\/orgel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/IMG-20210519-WA0011.jpg\",\"datePublished\":\"2026-05-30T19:40:57+00:00\",\"dateModified\":\"2026-05-31T10:32:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/unsere-kirchen\\\/kirche-dalherda\\\/orgel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/unsere-kirchen\\\/kirche-dalherda\\\/orgel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/unsere-kirchen\\\/kirche-dalherda\\\/orgel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/IMG-20210519-WA0011.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/IMG-20210519-WA0011.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/unsere-kirchen\\\/kirche-dalherda\\\/orgel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere Kirchen\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/unsere-kirchen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kirche Dalherda\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/unsere-kirchen\\\/kirche-dalherda\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Orgel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\",\"name\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"description\":\"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orgel - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/","og_locale":"de_DE","og_type":"article","og_title":"Orgel - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","og_description":"\u27a1\u00a0 Die urspr\u00fcngliche Orgel stammt vermutlich aus dem Jahr 1670. \u27a1\u00a0 1851\u00a0 Orgelbauer Ludwig Ratzmann aus dem th\u00fcringischem Ohrdruf baut eine neue Orgel mit 13 Registern, einem Manual und Pedal. \u27a1\u00a0 1946\u00a0 Die Orgel ist fast vollst\u00e4ndig zerst\u00f6rt, Werner Bosch (Kassel) \u00fcberholt die Ratzmann-Orgel. \u27a1\u00a0 Die Orgel wurde 1965 in einen \u201eunw\u00fcrdigen Zustand der Modernisierung\u201c [&hellip;]","og_url":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/","og_site_name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","article_modified_time":"2026-05-31T10:32:10+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0011.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/","url":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/","name":"Orgel - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0011.jpg","datePublished":"2026-05-30T19:40:57+00:00","dateModified":"2026-05-31T10:32:10+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/#primaryimage","url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0011.jpg","contentUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/06\/IMG-20210519-WA0011.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/orgel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-hettenhausen.de\/site\/"},{"@type":"ListItem","position":2,"name":"Unsere Kirchen","item":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/"},{"@type":"ListItem","position":3,"name":"Kirche Dalherda","item":"https:\/\/www.kirche-hettenhausen.de\/site\/unsere-kirchen\/kirche-dalherda\/"},{"@type":"ListItem","position":4,"name":"Orgel"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website","url":"https:\/\/www.kirche-hettenhausen.de\/site\/","name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-hettenhausen.de\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/pages\/17611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/comments?post=17611"}],"version-history":[{"count":12,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/pages\/17611\/revisions"}],"predecessor-version":[{"id":17834,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/pages\/17611\/revisions\/17834"}],"up":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/pages\/6775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media\/9023"}],"wp:attachment":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media?parent=17611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}