{"id":122,"count":7,"description":"Der Krabbeltreff trifft sich immer dienstags zwischen 10:00 und 12:00 Uhr im Martin-Luther-Haus. Wenn ihr mit eurem Krabbelkind Kontakt zu anderen Eltern und Kindern sucht, f\u00fcr Gespr\u00e4che, zum Spielen usw., seid ihr hier genau richtig. Schaut einfach mal vorbei!\r\n\r\nInformationen \u00fcber das Pfarramt, Tel .\u00a0 06656 307 oder <a href=\"mailto:pfarramt.hettenhausen@ekkw.de\">pfarramt.hettenhausen[at]ekkw.de<\/a>","link":"https:\/\/www.kirche-hettenhausen.de\/site\/mec-category\/krabbeltreff\/","name":"Krabbeltreff","slug":"krabbeltreff","taxonomy":"mec_category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda<\/title>\n<meta name=\"description\" content=\"Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda Der Krabbeltreff trifft sich immer dienstags zwischen 10:00 und 12:00 Uhr im Martin-Luther-Haus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-hettenhausen.de\/site\/mec-category\/krabbeltreff\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"og:description\" content=\"Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda Der Krabbeltreff trifft sich immer dienstags zwischen 10:00 und 12:00 Uhr im Martin-Luther-Haus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/mec-category\/krabbeltreff\/\" \/>\n<meta property=\"og:site_name\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/mec-category\\\/krabbeltreff\\\/\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/mec-category\\\/krabbeltreff\\\/\",\"name\":\"Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\"},\"description\":\"Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda Der Krabbeltreff trifft sich immer dienstags zwischen 10:00 und 12:00 Uhr im Martin-Luther-Haus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/mec-category\\\/krabbeltreff\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/mec-category\\\/krabbeltreff\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Krabbeltreff\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\",\"name\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"description\":\"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda Der Krabbeltreff trifft sich immer dienstags zwischen 10:00 und 12:00 Uhr im Martin-Luther-Haus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-hettenhausen.de\/site\/mec-category\/krabbeltreff\/","og_locale":"de_DE","og_type":"article","og_title":"Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","og_description":"Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda Der Krabbeltreff trifft sich immer dienstags zwischen 10:00 und 12:00 Uhr im Martin-Luther-Haus.","og_url":"https:\/\/www.kirche-hettenhausen.de\/site\/mec-category\/krabbeltreff\/","og_site_name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/mec-category\/krabbeltreff\/","url":"https:\/\/www.kirche-hettenhausen.de\/site\/mec-category\/krabbeltreff\/","name":"Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website"},"description":"Krabbeltreff - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda Der Krabbeltreff trifft sich immer dienstags zwischen 10:00 und 12:00 Uhr im Martin-Luther-Haus.","breadcrumb":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/mec-category\/krabbeltreff\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/mec-category\/krabbeltreff\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-hettenhausen.de\/site\/"},{"@type":"ListItem","position":2,"name":"Krabbeltreff"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website","url":"https:\/\/www.kirche-hettenhausen.de\/site\/","name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-hettenhausen.de\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec_category\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec_category"}],"about":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/taxonomies\/mec_category"}],"wp:post_type":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events?mec_category=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}