{"id":8019,"date":"2021-03-02T20:55:04","date_gmt":"2021-03-02T19:55:04","guid":{"rendered":"https:\/\/kirche-hettenhausen.de\/site\/?post_type=mec-events&#038;p=8019"},"modified":"2021-12-12T14:22:31","modified_gmt":"2021-12-12T13:22:31","slug":"gottesdienst-zum-4-advent-2","status":"publish","type":"mec-events","link":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/","title":{"rendered":"Gottesdienst zum 4. Advent"},"content":{"rendered":"<p>Gottesdienste in der Kirche Dalherda feiern wir regelm\u00e4\u00dfig an Sonn- und Feiertagen.<\/p>\n<p><strong>Wichtig: Bitte beachten Sie die aktuell g\u00fcltigen Zugangs- und Hygieneregelungen, die momentan befolgt werden m\u00fcssen. Sie finden sie <a href=\"https:\/\/www.kirche-hettenhausen.de\/site\/2021\/12\/aktuelle-infos\/\">hier<\/a>. Weitere Infos entnehmen Sie bitte den aktuellen Ank\u00fcndigungen!<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Advent<\/strong> ist die Zeit des Wartens und der Vorbereitung auf die Ankunft (lateinisch: adventus) des Gottessohnes Jesus Christus. Das Warten ist ein zentraler Aspekt dieser rund vierw\u00f6chigen Zeit im Dezember. Zum einen wartet man auf den Ged\u00e4chtnistag (Weihnachten), bei dem man sich an das erste Kommen Jesu in seiner Geburt erinnert. Zum anderen wartet man darauf, dass Jesus das zweite Mal erscheint, bei seiner erhofften Wiederkehr am Ende der Zeiten, zum J\u00fcngsten Gericht. Nach diesem Verst\u00e4ndnis sollen Bu\u00dfe, Fasten, Gebete und gute Werke in dieser Zeit im Mittelpunkt stehen.<\/p>\n<p>Jeder der vier Sonntage hat ein eigenes Gepr\u00e4ge und gestaltet so die weihnachtliche Vorgeschichte: 4. Advent &#8211; Maria (Mutter Jesu). An jedem Sonntag wird eine weitere Kerze auf dem Adventskranz entz\u00fcndet. Viele Menschen besuchen einen Adventsbasar oder einen Weihnachtsmarkt, um sich auf das Weihnachtsfest einzustimmen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wochenspruch<\/strong><br \/>\nFreuet euch in dem Herrn alle Wege, und abermals sage ich: Freuet euch! Der Herr ist nahe! <em>(Phil 4,4-5)<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gottesdienste in der Kirche Dalherda feiern wir regelm\u00e4\u00dfig an Sonn- und Feiertagen. Wichtig: Bitte beachten Sie die aktuell g\u00fcltigen Zugangs- und Hygieneregelungen, die momentan befolgt werden m\u00fcssen. Sie finden sie hier. Weitere Infos entnehmen Sie bitte den aktuellen Ank\u00fcndigungen! &nbsp; Advent ist die Zeit des Wartens und der Vorbereitung auf die Ankunft (lateinisch: adventus) des [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7162,"comment_status":"closed","ping_status":"closed","template":"","tags":[43,102,33],"mec_category":[109,114],"class_list":["post-8019","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-advent","tag-dalherda","tag-gottesdienst","mec_category-gottesdienst","mec_category-gottesdienst-dalherda"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gottesdienst zum 4. Advent - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda<\/title>\n<meta name=\"description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst zum 4. Advent\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gottesdienst zum 4. Advent - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"og:description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst zum 4. Advent\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-12T13:22:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"951\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-zum-4-advent-2\\\/\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-zum-4-advent-2\\\/\",\"name\":\"Gottesdienst zum 4. Advent - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-zum-4-advent-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-zum-4-advent-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kirche-Dalherda_6.jpg\",\"datePublished\":\"2021-03-02T19:55:04+00:00\",\"dateModified\":\"2021-12-12T13:22:31+00:00\",\"description\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst zum 4. Advent\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-zum-4-advent-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-zum-4-advent-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-zum-4-advent-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kirche-Dalherda_6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kirche-Dalherda_6.jpg\",\"width\":951,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-zum-4-advent-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gottesdienst zum 4. Advent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\",\"name\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"description\":\"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gottesdienst zum 4. Advent - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst zum 4. Advent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/","og_locale":"de_DE","og_type":"article","og_title":"Gottesdienst zum 4. Advent - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","og_description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst zum 4. Advent","og_url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/","og_site_name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","article_modified_time":"2021-12-12T13:22:31+00:00","og_image":[{"width":951,"height":1600,"url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/","url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/","name":"Gottesdienst zum 4. Advent - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_6.jpg","datePublished":"2021-03-02T19:55:04+00:00","dateModified":"2021-12-12T13:22:31+00:00","description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst zum 4. Advent","breadcrumb":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/#primaryimage","url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_6.jpg","contentUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_6.jpg","width":951,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-zum-4-advent-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-hettenhausen.de\/site\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/"},{"@type":"ListItem","position":3,"name":"Gottesdienst zum 4. Advent"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website","url":"https:\/\/www.kirche-hettenhausen.de\/site\/","name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-hettenhausen.de\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events\/8019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/comments?post=8019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media\/7162"}],"wp:attachment":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media?parent=8019"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/tags?post=8019"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec_category?post=8019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}