{"id":15504,"date":"2024-11-02T15:09:44","date_gmt":"2024-11-02T14:09:44","guid":{"rendered":"https:\/\/kirche-hettenhausen.de\/site\/?post_type=mec-events&#038;p=15504"},"modified":"2024-11-02T15:11:08","modified_gmt":"2024-11-02T14:11:08","slug":"20-jahre-gospel-of-joy","status":"publish","type":"mec-events","link":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/","title":{"rendered":"20 Jahre Gospel of Joy"},"content":{"rendered":"<p>mit Liedermacher und Dekan Dr. Thorsten Waap<\/p>\n<p>Eintritt frei<\/p>\n","protected":false},"excerpt":{"rendered":"<p>mit Liedermacher und Dekan Dr. Thorsten Waap Eintritt frei<\/p>\n","protected":false},"author":2,"featured_media":15503,"comment_status":"closed","ping_status":"closed","template":"","tags":[219,36,7,67,39],"mec_category":[139],"class_list":["post-15504","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-kirchenkreis-fulda","tag-musik","tag-pfarrer","tag-singen","tag-veranstaltungen","mec_category-veranstaltungen-feste"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>20 Jahre Gospel of Joy - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda<\/title>\n<meta name=\"description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - 20 Jahre Gospel of Joy -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20 Jahre Gospel of Joy - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"og:description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - 20 Jahre Gospel of Joy -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/\" \/>\n<meta property=\"og:site_name\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-02T14:11:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2024\/11\/Gospel-of-Joy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/20-jahre-gospel-of-joy\\\/\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/20-jahre-gospel-of-joy\\\/\",\"name\":\"20 Jahre Gospel of Joy - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/20-jahre-gospel-of-joy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/20-jahre-gospel-of-joy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Gospel-of-Joy.jpg\",\"datePublished\":\"2024-11-02T14:09:44+00:00\",\"dateModified\":\"2024-11-02T14:11:08+00:00\",\"description\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - 20 Jahre Gospel of Joy -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/20-jahre-gospel-of-joy\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/20-jahre-gospel-of-joy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/20-jahre-gospel-of-joy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Gospel-of-Joy.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Gospel-of-Joy.jpg\",\"width\":1080,\"height\":1512,\"caption\":\"Dekan Dr. Thorsten Waap\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/20-jahre-gospel-of-joy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"20 Jahre Gospel of Joy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\",\"name\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"description\":\"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20 Jahre Gospel of Joy - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - 20 Jahre Gospel of Joy -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/","og_locale":"de_DE","og_type":"article","og_title":"20 Jahre Gospel of Joy - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","og_description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - 20 Jahre Gospel of Joy -","og_url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/","og_site_name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","article_modified_time":"2024-11-02T14:11:08+00:00","og_image":[{"width":1080,"height":1512,"url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2024\/11\/Gospel-of-Joy.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/","url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/","name":"20 Jahre Gospel of Joy - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2024\/11\/Gospel-of-Joy.jpg","datePublished":"2024-11-02T14:09:44+00:00","dateModified":"2024-11-02T14:11:08+00:00","description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - 20 Jahre Gospel of Joy -","breadcrumb":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/#primaryimage","url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2024\/11\/Gospel-of-Joy.jpg","contentUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2024\/11\/Gospel-of-Joy.jpg","width":1080,"height":1512,"caption":"Dekan Dr. Thorsten Waap"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/20-jahre-gospel-of-joy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-hettenhausen.de\/site\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/"},{"@type":"ListItem","position":3,"name":"20 Jahre Gospel of Joy"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website","url":"https:\/\/www.kirche-hettenhausen.de\/site\/","name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-hettenhausen.de\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events\/15504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/comments?post=15504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media\/15503"}],"wp:attachment":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media?parent=15504"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/tags?post=15504"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec_category?post=15504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}