{"id":15147,"date":"2024-09-07T18:45:04","date_gmt":"2024-09-07T16:45:04","guid":{"rendered":"https:\/\/kirche-hettenhausen.de\/site\/?post_type=mec-events&#038;p=15147"},"modified":"2024-09-07T18:45:04","modified_gmt":"2024-09-07T16:45:04","slug":"gottesdienst-mit-abendmahl-1-weihnachtstag-4","status":"publish","type":"mec-events","link":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/","title":{"rendered":"Gottesdienst mit Abendmahl &#8222;1. Weihnachtstag&#8220;"},"content":{"rendered":"<p>Gottesdienste in der Ev.-luth. Pfarrkirche St. Georg Hettenhausen feiern wir regelm\u00e4\u00dfig an Sonn- und Feiertagen.<\/p>\n<p>&nbsp;<\/p>\n<p>Christen in aller Welt feiern an <strong>Weihnachten<\/strong> die Geburt von Jesus. Nach der biblischen Weihnachtsgeschichte kam er in einem Stall in Bethlehem zur Welt. Ein heller Stern leuchtete \u00fcber der Stadt, als Zeichen, dass ein besonderes Kind geboren ist. Nach christlichem Glauben ist Gott als Mensch zur Welt gekommen in diesem Kind. Zum Weihnachtsfest geh\u00f6ren der Heiligabend am 24. Dezember und zwei Weihnachtsfeiertage.<\/p>\n<p>Der <b>Heilige Abend<\/b> am 24.\u00a0Dezember, auch <b>Heiligabend<\/b> oder <b>Weihnachtsabend<\/b> genannt, ist der Vorabend des Weihnachtsfestes (Fest der Geburt Jesu Christi). Als <b>Heilige Nacht<\/b> oder als <b>Christnacht<\/b> wird die Nacht vom 24. auf den 25. Dezember bezeichnet.<\/p>\n<p>In der Kirche wird Weihnachten mit vielen Gottesdiensten gefeiert. Zum beliebten Familienfest schm\u00fccken viele ihr Zuhause mit Kerzen, einem Tannenbaum oder einer Weihnachtskrippe. Und es gibt Geschenke \u2013 weil auch die Weisen aus dem Morgenland, die dem Weihnachtsstern gefolgt waren, Jesus beschenkt haben.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wochenspruch<\/strong><br \/>\nDas Wort ward Fleisch und wohnte unter uns, und wir sahen seine Herrlichkeit. <em>(Joh 1,14)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gottesdienste in der Ev.-luth. Pfarrkirche St. Georg Hettenhausen feiern wir regelm\u00e4\u00dfig an Sonn- und Feiertagen. &nbsp; Christen in aller Welt feiern an Weihnachten die Geburt von Jesus. Nach der biblischen Weihnachtsgeschichte kam er in einem Stall in Bethlehem zur Welt. Ein heller Stern leuchtete \u00fcber der Stadt, als Zeichen, dass ein besonderes Kind geboren ist. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6683,"comment_status":"closed","ping_status":"closed","template":"","tags":[33,128,34,45],"mec_category":[109,113],"class_list":["post-15147","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-gottesdienst","tag-hettenhausen","tag-pfarrkirche-st-georg","tag-weihnachten","mec_category-gottesdienst","mec_category-gottesdienst-hettenhausen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gottesdienst mit Abendmahl &quot;1. Weihnachtstag&quot; - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda<\/title>\n<meta name=\"description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst mit Abendmahl &quot;1. Weihnachtstag&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gottesdienst mit Abendmahl &quot;1. Weihnachtstag&quot; - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"og:description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst mit Abendmahl &quot;1. Weihnachtstag&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2020\/12\/20201224_111417.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\\\/\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\\\/\",\"name\":\"Gottesdienst mit Abendmahl \\\"1. Weihnachtstag\\\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201224_111417.jpg\",\"datePublished\":\"2024-09-07T16:45:04+00:00\",\"description\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst mit Abendmahl \\\"1. Weihnachtstag\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201224_111417.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201224_111417.jpg\",\"width\":1024,\"height\":768,\"caption\":\"Weihnachten 2020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gottesdienst mit Abendmahl &#8222;1. Weihnachtstag&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\",\"name\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"description\":\"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gottesdienst mit Abendmahl \"1. Weihnachtstag\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst mit Abendmahl \"1. Weihnachtstag\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/","og_locale":"de_DE","og_type":"article","og_title":"Gottesdienst mit Abendmahl \"1. Weihnachtstag\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","og_description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst mit Abendmahl \"1. Weihnachtstag\"","og_url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/","og_site_name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2020\/12\/20201224_111417.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/","url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/","name":"Gottesdienst mit Abendmahl \"1. Weihnachtstag\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2020\/12\/20201224_111417.jpg","datePublished":"2024-09-07T16:45:04+00:00","description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Gottesdienst mit Abendmahl \"1. Weihnachtstag\"","breadcrumb":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/#primaryimage","url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2020\/12\/20201224_111417.jpg","contentUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2020\/12\/20201224_111417.jpg","width":1024,"height":768,"caption":"Weihnachten 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/gottesdienst-mit-abendmahl-1-weihnachtstag-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-hettenhausen.de\/site\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/"},{"@type":"ListItem","position":3,"name":"Gottesdienst mit Abendmahl &#8222;1. Weihnachtstag&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website","url":"https:\/\/www.kirche-hettenhausen.de\/site\/","name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-hettenhausen.de\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events\/15147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/comments?post=15147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media\/6683"}],"wp:attachment":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media?parent=15147"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/tags?post=15147"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec_category?post=15147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}