{"id":14898,"date":"2024-05-17T21:45:34","date_gmt":"2024-05-17T19:45:34","guid":{"rendered":"https:\/\/kirche-hettenhausen.de\/site\/?post_type=mec-events&#038;p=14898"},"modified":"2024-07-13T14:20:20","modified_gmt":"2024-07-13T12:20:20","slug":"klangwelten-mit-ronja-schelling","status":"publish","type":"mec-events","link":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/","title":{"rendered":"Klangwelten mit Ronja Schelling"},"content":{"rendered":"<p><strong>Eine Reise durch moderne Melodien<\/strong><\/p>\n<p>Erleben Sie die Magie von Klavier, Gitarre und Gesang mit einer einzigartigen Fusion aus Eigenkompositionen und inspirierenden Coversongs.<\/p>\n<p>Weitere Infos <a href=\"https:\/\/www.kirche-hettenhausen.de\/site\/2024\/05\/klangwelten-mit-ronja-schelling\/\"><strong>hier<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine Reise durch moderne Melodien Erleben Sie die Magie von Klavier, Gitarre und Gesang mit einer einzigartigen Fusion aus Eigenkompositionen und inspirierenden Coversongs. Weitere Infos hier<\/p>\n","protected":false},"author":2,"featured_media":14972,"comment_status":"closed","ping_status":"closed","template":"","tags":[128,36,34,67,39],"mec_category":[139],"class_list":["post-14898","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-hettenhausen","tag-musik","tag-pfarrkirche-st-georg","tag-singen","tag-veranstaltungen","mec_category-veranstaltungen-feste"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Klangwelten mit Ronja Schelling - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klangwelten mit Ronja Schelling - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"og:description\" content=\"Eine Reise durch moderne Melodien Erleben Sie die Magie von Klavier, Gitarre und Gesang mit einer einzigartigen Fusion aus Eigenkompositionen und inspirierenden Coversongs. Weitere Infos hier\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/\" \/>\n<meta property=\"og:site_name\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-13T12:20:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2024\/07\/Klangwelten-Ronja-Schelling.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1150\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/klangwelten-mit-ronja-schelling\\\/\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/klangwelten-mit-ronja-schelling\\\/\",\"name\":\"Klangwelten mit Ronja Schelling - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/klangwelten-mit-ronja-schelling\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/klangwelten-mit-ronja-schelling\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Klangwelten-Ronja-Schelling.jpg\",\"datePublished\":\"2024-05-17T19:45:34+00:00\",\"dateModified\":\"2024-07-13T12:20:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/klangwelten-mit-ronja-schelling\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/klangwelten-mit-ronja-schelling\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/klangwelten-mit-ronja-schelling\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Klangwelten-Ronja-Schelling.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Klangwelten-Ronja-Schelling.jpg\",\"width\":1150,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/klangwelten-mit-ronja-schelling\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Klangwelten mit Ronja Schelling\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\",\"name\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"description\":\"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klangwelten mit Ronja Schelling - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/","og_locale":"de_DE","og_type":"article","og_title":"Klangwelten mit Ronja Schelling - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","og_description":"Eine Reise durch moderne Melodien Erleben Sie die Magie von Klavier, Gitarre und Gesang mit einer einzigartigen Fusion aus Eigenkompositionen und inspirierenden Coversongs. Weitere Infos hier","og_url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/","og_site_name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","article_modified_time":"2024-07-13T12:20:20+00:00","og_image":[{"width":1150,"height":1600,"url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2024\/07\/Klangwelten-Ronja-Schelling.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/","url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/","name":"Klangwelten mit Ronja Schelling - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2024\/07\/Klangwelten-Ronja-Schelling.jpg","datePublished":"2024-05-17T19:45:34+00:00","dateModified":"2024-07-13T12:20:20+00:00","breadcrumb":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/#primaryimage","url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2024\/07\/Klangwelten-Ronja-Schelling.jpg","contentUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2024\/07\/Klangwelten-Ronja-Schelling.jpg","width":1150,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/klangwelten-mit-ronja-schelling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-hettenhausen.de\/site\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/"},{"@type":"ListItem","position":3,"name":"Klangwelten mit Ronja Schelling"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website","url":"https:\/\/www.kirche-hettenhausen.de\/site\/","name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-hettenhausen.de\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events\/14898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/comments?post=14898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media\/14972"}],"wp:attachment":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media?parent=14898"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/tags?post=14898"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec_category?post=14898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}