{"id":10970,"date":"2022-01-23T17:45:38","date_gmt":"2022-01-23T16:45:38","guid":{"rendered":"https:\/\/kirche-hettenhausen.de\/site\/?post_type=mec-events&#038;p=10970"},"modified":"2026-06-06T09:41:45","modified_gmt":"2026-06-06T07:41:45","slug":"kirmes-gottesdienst-16-so-n-trinitatis","status":"publish","type":"mec-events","link":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/","title":{"rendered":"Kirmes-Gottesdienst &#8222;16. So. n. Trinitatis&#8220;"},"content":{"rendered":"<p>Gottesdienste in der Kirche Dalherda feiern wir regelm\u00e4\u00dfig an Sonn- und Feiertagen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wochenspruch<\/strong><br \/>\nJesus Christus hat dem Tode die Macht genommen und das Leben und ein unverg\u00e4ngliches Wesen ans Licht gebracht durch das Evangelium. <em>(1. Tim 1,10<\/em><em>)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gottesdienste in der Kirche Dalherda feiern wir regelm\u00e4\u00dfig an Sonn- und Feiertagen. &nbsp; Wochenspruch Jesus Christus hat dem Tode die Macht genommen und das Leben und ein unverg\u00e4ngliches Wesen ans Licht gebracht durch das Evangelium. (1. Tim 1,10)<\/p>\n","protected":false},"author":2,"featured_media":7161,"comment_status":"closed","ping_status":"closed","template":"","tags":[102,33,211,39],"mec_category":[109,114],"class_list":["post-10970","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-dalherda","tag-gottesdienst","tag-kirmes","tag-veranstaltungen","mec_category-gottesdienst","mec_category-gottesdienst-dalherda"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kirmes-Gottesdienst &quot;16. So. n. Trinitatis&quot; - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda<\/title>\n<meta name=\"description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Kirmes-Gottesdienst &quot;16. So. n. Trinitatis&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kirmes-Gottesdienst &quot;16. So. n. Trinitatis&quot; - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"og:description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Kirmes-Gottesdienst &quot;16. So. n. Trinitatis&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/\" \/>\n<meta property=\"og:site_name\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-06T07:41:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1469\" \/>\n\t<meta property=\"og:image:height\" content=\"1134\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/kirmes-gottesdienst-16-so-n-trinitatis\\\/\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/kirmes-gottesdienst-16-so-n-trinitatis\\\/\",\"name\":\"Kirmes-Gottesdienst \\\"16. So. n. Trinitatis\\\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/kirmes-gottesdienst-16-so-n-trinitatis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/kirmes-gottesdienst-16-so-n-trinitatis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kirche-Dalherda_5.jpg\",\"datePublished\":\"2022-01-23T16:45:38+00:00\",\"dateModified\":\"2026-06-06T07:41:45+00:00\",\"description\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Kirmes-Gottesdienst \\\"16. So. n. Trinitatis\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/kirmes-gottesdienst-16-so-n-trinitatis\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/kirmes-gottesdienst-16-so-n-trinitatis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/kirmes-gottesdienst-16-so-n-trinitatis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kirche-Dalherda_5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kirche-Dalherda_5.jpg\",\"width\":1469,\"height\":1134},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/kirmes-gottesdienst-16-so-n-trinitatis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kirmes-Gottesdienst &#8222;16. So. n. Trinitatis&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\",\"name\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"description\":\"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kirmes-Gottesdienst \"16. So. n. Trinitatis\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Kirmes-Gottesdienst \"16. So. n. Trinitatis\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/","og_locale":"de_DE","og_type":"article","og_title":"Kirmes-Gottesdienst \"16. So. n. Trinitatis\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","og_description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Kirmes-Gottesdienst \"16. So. n. Trinitatis\"","og_url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/","og_site_name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","article_modified_time":"2026-06-06T07:41:45+00:00","og_image":[{"width":1469,"height":1134,"url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/","url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/","name":"Kirmes-Gottesdienst \"16. So. n. Trinitatis\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_5.jpg","datePublished":"2022-01-23T16:45:38+00:00","dateModified":"2026-06-06T07:41:45+00:00","description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Kirmes-Gottesdienst \"16. So. n. Trinitatis\"","breadcrumb":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/#primaryimage","url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_5.jpg","contentUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_5.jpg","width":1469,"height":1134},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/kirmes-gottesdienst-16-so-n-trinitatis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-hettenhausen.de\/site\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/"},{"@type":"ListItem","position":3,"name":"Kirmes-Gottesdienst &#8222;16. So. n. Trinitatis&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website","url":"https:\/\/www.kirche-hettenhausen.de\/site\/","name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-hettenhausen.de\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events\/10970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/comments?post=10970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media\/7161"}],"wp:attachment":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media?parent=10970"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/tags?post=10970"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec_category?post=10970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}