{"id":10958,"date":"2022-01-23T16:08:39","date_gmt":"2022-01-23T15:08:39","guid":{"rendered":"https:\/\/kirche-hettenhausen.de\/site\/?post_type=mec-events&#038;p=10958"},"modified":"2023-01-15T19:35:06","modified_gmt":"2023-01-15T18:35:06","slug":"abend-gottesdienst-5-so-n-trinitatis-4","status":"publish","type":"mec-events","link":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/","title":{"rendered":"Abend-Gottesdienst &#8222;5. So. n. Trinitatis&#8220;"},"content":{"rendered":"<p>Gottesdienste in der Kirche Dalherda feiern wir regelm\u00e4\u00dfig an Sonn- und Feiertagen.<\/p>\n<p>Einmal im Monat findet in der Kirche Dalherda in den Sommermonaten ein Abendgottesdienst statt.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wochenspruch<\/strong><br \/>\nAus Gnade seid ihr gerettet durch Glauben, und das nicht aus euch: Gottes Gabe ist es. <em>(Eph 2,8)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gottesdienste in der Kirche Dalherda feiern wir regelm\u00e4\u00dfig an Sonn- und Feiertagen. Einmal im Monat findet in der Kirche Dalherda in den Sommermonaten ein Abendgottesdienst statt. &nbsp; Wochenspruch Aus Gnade seid ihr gerettet durch Glauben, und das nicht aus euch: Gottes Gabe ist es. (Eph 2,8)<\/p>\n","protected":false},"author":2,"featured_media":7159,"comment_status":"closed","ping_status":"closed","template":"","tags":[102,33],"mec_category":[109,114],"class_list":["post-10958","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-dalherda","tag-gottesdienst","mec_category-gottesdienst","mec_category-gottesdienst-dalherda"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abend-Gottesdienst &quot;5. So. n. Trinitatis&quot; - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda<\/title>\n<meta name=\"description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Abend-Gottesdienst &quot;5. So. n. Trinitatis&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abend-Gottesdienst &quot;5. So. n. Trinitatis&quot; - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"og:description\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Abend-Gottesdienst &quot;5. So. n. Trinitatis&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-15T18:35:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1058\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/abend-gottesdienst-5-so-n-trinitatis-4\\\/\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/abend-gottesdienst-5-so-n-trinitatis-4\\\/\",\"name\":\"Abend-Gottesdienst \\\"5. So. n. Trinitatis\\\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/abend-gottesdienst-5-so-n-trinitatis-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/abend-gottesdienst-5-so-n-trinitatis-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kirche-Dalherda_3.jpg\",\"datePublished\":\"2022-01-23T15:08:39+00:00\",\"dateModified\":\"2023-01-15T18:35:06+00:00\",\"description\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Abend-Gottesdienst \\\"5. So. n. Trinitatis\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/abend-gottesdienst-5-so-n-trinitatis-4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/abend-gottesdienst-5-so-n-trinitatis-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/abend-gottesdienst-5-so-n-trinitatis-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kirche-Dalherda_3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Kirche-Dalherda_3.jpg\",\"width\":1058,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/abend-gottesdienst-5-so-n-trinitatis-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abend-Gottesdienst &#8222;5. So. n. Trinitatis&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/\",\"name\":\"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"description\":\"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kirche-hettenhausen.de\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abend-Gottesdienst \"5. So. n. Trinitatis\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Abend-Gottesdienst \"5. So. n. Trinitatis\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/","og_locale":"de_DE","og_type":"article","og_title":"Abend-Gottesdienst \"5. So. n. Trinitatis\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","og_description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Abend-Gottesdienst \"5. So. n. Trinitatis\"","og_url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/","og_site_name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","article_modified_time":"2023-01-15T18:35:06+00:00","og_image":[{"width":1058,"height":1600,"url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/","url":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/","name":"Abend-Gottesdienst \"5. So. n. Trinitatis\" - Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","isPartOf":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/#primaryimage"},"image":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_3.jpg","datePublished":"2022-01-23T15:08:39+00:00","dateModified":"2023-01-15T18:35:06+00:00","description":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda - Abend-Gottesdienst \"5. So. n. Trinitatis\"","breadcrumb":{"@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/#primaryimage","url":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_3.jpg","contentUrl":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-content\/uploads\/2021\/01\/Kirche-Dalherda_3.jpg","width":1058,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/abend-gottesdienst-5-so-n-trinitatis-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kirche-hettenhausen.de\/site\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.kirche-hettenhausen.de\/site\/events\/"},{"@type":"ListItem","position":3,"name":"Abend-Gottesdienst &#8222;5. So. n. Trinitatis&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/www.kirche-hettenhausen.de\/site\/#website","url":"https:\/\/www.kirche-hettenhausen.de\/site\/","name":"Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","description":"Homepage der Ev.-luth. Kirchengemeinde Hettenhausen - Dalherda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kirche-hettenhausen.de\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events\/10958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/comments?post=10958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media\/7159"}],"wp:attachment":[{"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/media?parent=10958"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/tags?post=10958"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.kirche-hettenhausen.de\/site\/wp-json\/wp\/v2\/mec_category?post=10958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}